{"id":9359,"date":"2013-05-06T10:51:17","date_gmt":"2013-05-06T14:51:17","guid":{"rendered":"http:\/\/humanidades.uach.cl\/respaldo\/?p=9359"},"modified":"2013-05-06T10:51:17","modified_gmt":"2013-05-06T14:51:17","slug":"se-exhibira-documental-personapaisaje-el-descanso-un-rito-funebre-mapuche","status":"publish","type":"post","link":"https:\/\/humanidades.uach.cl\/respaldo\/2013\/05\/06\/se-exhibira-documental-personapaisaje-el-descanso-un-rito-funebre-mapuche\/","title":{"rendered":"Se exhibir\u00e1 documental Persona\/Paisaje: el descanso, un rito f\u00fanebre mapuche"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/humanidades.uach.cl\/respaldo\/2013\/05\/06\/se-exhibira-documental-personapaisaje-el-descanso-un-rito-funebre-mapuche\/caratula-i-3\/\" rel=\"attachment wp-att-9360\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-9360\" alt=\"Caratula I\" src=\"http:\/\/humanidades.uach.cl\/respaldo\/wp-content\/uploads\/Caratula-I2-250x250.jpg\" width=\"250\" height=\"250\" srcset=\"https:\/\/humanidades.uach.cl\/respaldo\/wp-content\/uploads\/Caratula-I2-250x250.jpg 250w, https:\/\/humanidades.uach.cl\/respaldo\/wp-content\/uploads\/Caratula-I2-100x100.jpg 100w, https:\/\/humanidades.uach.cl\/respaldo\/wp-content\/uploads\/Caratula-I2.jpg 600w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/a>El documental de 29 minutos, describe \u201cEl\u00a0<i>descanso\u201d,<\/i> un rito f\u00fanebre mapuche que se realiza posteriormente al velorio de una persona y antes de la partida final hacia el cementerio. Basado en un discurso al\u00a0<i>p\u00fcll\u00fc<\/i>\u00a0(esp\u00edritu) de la persona fallecida con objeto de informarle su separaci\u00f3n del mundo de los vivos.<\/p>\n<p style=\"text-align: justify;\">La producci\u00f3n realizada a partir de los testimonios de tres mujeres y un hombre, pertenecientes a tres comunidades mapuches, presta especial atenci\u00f3n a la relaci\u00f3n que se establece, entre la ceremonia mortuoria, el <i>p\u00fcll\u00fc<\/i> de la persona fallecida y su familia; y entre la materialidad subsecuente y el paisaje circundante.<\/p>\n<p style=\"text-align: justify;\">Realizado en los sectores de Lago Neltume y Punahue, comuna de Panguipulli, pre-cordillera de la Regi\u00f3n de Los R\u00edos, el documental fue estrenado en el Cine Club de la UACh el 19 de abril; present\u00e1ndose posteriormente en el Departamento de Antropolog\u00eda de la Universidad Alberto Hurtado, en su C\u00e1tedra Cultura e Identidad Latinoamericana, en Santiago.<\/p>\n<p style=\"text-align: justify;\">As\u00ed tambi\u00e9n, est\u00e1 programada su exhibici\u00f3n en:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Casona Cultural de Panguipulli, Panguipulli. Martes 7 de mayo de 2013, 16:00 hrs.<\/li>\n<li>Auditorio Centro de Innovaci\u00f3n Docente Facultad de Filosof\u00eda y Humanidades, Universidad Austral de Chile: (Fecha y hora a confirmar).<\/li>\n<li>Escuela Rural Lago Neltume, Lago Neltume: (Fecha y hora a confirmar).<\/li>\n<li>Infocentro Neltume, Neltume: (Fecha y hora a confirmar).<\/li>\n<li>Biblioteca de Puente Alto, Santiago: (Fecha y hora a confirmar).<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">En la exhibici\u00f3n contaremos con la presencia de su autor Pablo Rojas, quien presentar\u00e1 una mirada anal\u00edtica de la producci\u00f3n. La entrada es liberada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Centro Transdisciplinario de Estudios Ambientales y desarrollo Humano Sostenible de la Universidad Austral de Chile (CEAM-UACh) presentar\u00e1 la producci\u00f3n este jueves 9 de mayo a las 18:30 hrs. <\/p>\n","protected":false},"author":3,"featured_media":9360,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[22,1,68],"tags":[1022,735],"_links":{"self":[{"href":"https:\/\/humanidades.uach.cl\/respaldo\/wp-json\/wp\/v2\/posts\/9359"}],"collection":[{"href":"https:\/\/humanidades.uach.cl\/respaldo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/humanidades.uach.cl\/respaldo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/humanidades.uach.cl\/respaldo\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/humanidades.uach.cl\/respaldo\/wp-json\/wp\/v2\/comments?post=9359"}],"version-history":[{"count":3,"href":"https:\/\/humanidades.uach.cl\/respaldo\/wp-json\/wp\/v2\/posts\/9359\/revisions"}],"predecessor-version":[{"id":9363,"href":"https:\/\/humanidades.uach.cl\/respaldo\/wp-json\/wp\/v2\/posts\/9359\/revisions\/9363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/humanidades.uach.cl\/respaldo\/wp-json\/wp\/v2\/media\/9360"}],"wp:attachment":[{"href":"https:\/\/humanidades.uach.cl\/respaldo\/wp-json\/wp\/v2\/media?parent=9359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/humanidades.uach.cl\/respaldo\/wp-json\/wp\/v2\/categories?post=9359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/humanidades.uach.cl\/respaldo\/wp-json\/wp\/v2\/tags?post=9359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}